{"id":10421,"date":"2023-08-18T06:14:09","date_gmt":"2023-08-18T06:14:09","guid":{"rendered":"https:\/\/china-maching.com\/?p=10421"},"modified":"2023-08-29T01:57:50","modified_gmt":"2023-08-29T01:57:50","slug":"aluminum-bending-techniques-and-tips","status":"publish","type":"post","link":"https:\/\/china-maching.com\/pt\/tecnicas-e-pontas-de-dobra-de-aluminio\/","title":{"rendered":"Dobragem de Alum\u00ednio: T\u00e9cnicas e Dicas"},"content":{"rendered":"<h2>Como dobrar alum\u00ednio<\/h2>\n<figure id=\"attachment_10423\" aria-describedby=\"caption-attachment-10423\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-10423\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23.png\" alt=\"No assentamento, h\u00e1 folga angular entre o pun\u00e7\u00e3o e a matriz. O pun\u00e7\u00e3o desce e o material envolve a ponta do pun\u00e7\u00e3o. \u00c0 medida que o pun\u00e7\u00e3o continua a aplicar press\u00e3o, o material \u00e9 for\u00e7ado para baixo para se adequar ao \u00e2ngulo da matriz.\" width=\"1000\" height=\"269\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23.png 1000w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23-300x81.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23-768x207.png 768w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23-18x5.png 18w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-23-250x67.png 250w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><figcaption id=\"caption-attachment-10423\" class=\"wp-caption-text\"><strong>No assentamento, h\u00e1 folga angular entre o pun\u00e7\u00e3o e a matriz. O pun\u00e7\u00e3o desce e o material envolve a ponta do pun\u00e7\u00e3o. \u00c0 medida que o pun\u00e7\u00e3o continua a aplicar press\u00e3o, o material \u00e9 for\u00e7ado para baixo para se adequar ao \u00e2ngulo da matriz.<\/strong><br><strong>fonte da imagem: https:\/\/www.thefabricator.com\/<\/strong><\/figcaption><\/figure>\n<p><strong>Dobrar alum\u00ednio<\/strong> est\u00e1 deformando o metal para formar uma curva ou \u00e2ngulo. \u00c9 uma t\u00e9cnica essencial em v\u00e1rias ind\u00fastrias, incluindo constru\u00e7\u00e3o, automotiva e aeroespacial. As propriedades leves, dur\u00e1veis e resistentes \u00e0 corros\u00e3o do alum\u00ednio o tornam uma escolha popular para muitas aplica\u00e7\u00f5es. No entanto, dobrar alum\u00ednio requer conhecimento e habilidades para garantir resultados bem-sucedidos.<\/p>\n<h3>Qual \u00e9 o melhor m\u00e9todo para dobrar alum\u00ednio?<\/h3>\n<p>O melhor m\u00e9todo para dobrar alum\u00ednio depende de v\u00e1rios fatores, incluindo espessura, liga e uso pretendido. As formas mais comuns s\u00e3o dobra de freio de prensa, dobra de rolo e dobra de tra\u00e7\u00e3o rotativa. A dobra do freio de press\u00e3o se adapta a chapas mais grossas e produz dobras limpas e precisas. A dobra por rolo \u00e9 ideal para formas grandes e curvas, enquanto a dobra por estiramento rotativo se adapta a pe\u00e7as pequenas e delicadas. Cada m\u00e9todo requer ferramentas e conhecimentos espec\u00edficos para alcan\u00e7ar os resultados desejados.<\/p>\n<div class=\"ast-oembed-container\" style=\"height: 100%;\"><iframe title=\"dobra de alum\u00ednio\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/13fONdCX9P8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3>Qual \u00e9 o raio de curvatura ideal para o alum\u00ednio?<\/h3>\n<p>O raio de curvatura ideal para o alum\u00ednio depende da espessura, liga e temperamento do material. Geralmente, o raio de curvatura recomendado para o alum\u00ednio \u00e9 de pelo menos 1,5 vezes a espessura do material para a maioria das ligas. No entanto, algumas ligas podem exigir um raio de curvatura maior devido \u00e0s suas propriedades inerentes. Dobrar o alum\u00ednio al\u00e9m de seu raio ideal pode causar rachaduras, enrugamentos ou outros defeitos que podem comprometer a resist\u00eancia e a durabilidade do material.<\/p>\n<h3>Como recozir o alum\u00ednio para dobrar?<\/h3>\n<p>O recozimento do alum\u00ednio envolve aquecer o metal a uma temperatura espec\u00edfica e resfri\u00e1-lo lentamente para melhorar sua elasticidade e reduzir sua dureza. O recozimento do alum\u00ednio antes da dobra torna o material mais male\u00e1vel e mais f\u00e1cil de deformar sem rachar ou rasgar. A temperatura e o tempo ideais para o recozimento dependem da liga de alum\u00ednio e da espessura. Uma vez que o alum\u00ednio tenha sido recozido, deve-se permitir que ele esfrie lentamente para evitar choque t\u00e9rmico.<\/p>\n<p><strong>Recomendar Leitura: <a href=\"https:\/\/china-maching.com\/pt\/fabricacao-de-chapas-metalicas\/\" target=\"_blank\">FABRICA\u00c7\u00c3O DE CHAPA<\/a><br>\n<\/strong><\/p>\n<h3>Quais s\u00e3o as ligas recomendadas para dobrar alum\u00ednio?<\/h3>\n<p>Nem todas as ligas de alum\u00ednio s\u00e3o adequadas para dobrar. Algumas ligas s\u00e3o muito fr\u00e1geis ou duras para formar adequadamente sem rachar ou rasgar. As ligas mais usadas para torneamento s\u00e3o as s\u00e9ries 3003, 5052 e 6061. Cada liga possui propriedades espec\u00edficas que as tornam adequadas para determinadas aplica\u00e7\u00f5es. A s\u00e9rie 3003 \u00e9 conhecida por sua excelente formabilidade e soldabilidade, tornando-a uma escolha popular na constru\u00e7\u00e3o e fabrica\u00e7\u00e3o em geral. A s\u00e9rie 5052 \u00e9 resistente \u00e0 corros\u00e3o, tornando-a adequada para aplica\u00e7\u00f5es mar\u00edtimas e externas. A s\u00e9rie 6061 possui alta resist\u00eancia e usinabilidade, tornando-a ideal para componentes aeroespaciais e automotivos.<\/p>\n<h3>Quais fatores afetam o processo de dobra do alum\u00ednio?<\/h3>\n<p>V\u00e1rios fatores podem afetar o processo de dobra do alum\u00ednio, incluindo espessura, liga, t\u00eampera e forma do material, bem como o m\u00e9todo de dobra e as ferramentas usadas. Folhas de alum\u00ednio mais grossas podem exigir mais for\u00e7a ou um raio de curvatura maior para evitar rachaduras. Diferentes ligas podem ter diferentes raios de curvatura ideais e temperaturas de recozimento. A dire\u00e7\u00e3o da estrutura do gr\u00e3o no metal tamb\u00e9m pode afetar suas propriedades de flex\u00e3o. \u00c9 essencial selecionar a liga e o m\u00e9todo apropriados para a aplica\u00e7\u00e3o pretendida e considerar todos os fatores que podem afetar o processo de dobra.<\/p>\n<h2>Problemas comuns na dobra de alum\u00ednio<\/h2>\n<figure id=\"attachment_10426\" aria-describedby=\"caption-attachment-10426\" style=\"width: 662px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-10426\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-34.png\" alt=\"Diagrama esquem\u00e1tico do teste de flex\u00e3o de tr\u00eas pontos\" width=\"662\" height=\"210\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-34.png 662w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-34-300x95.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-34-18x6.png 18w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-34-250x79.png 250w\" sizes=\"(max-width: 662px) 100vw, 662px\"><figcaption id=\"caption-attachment-10426\" class=\"wp-caption-text\"><strong>Diagrama esquem\u00e1tico do teste de flex\u00e3o de tr\u00eas pontos<\/strong><\/figcaption><\/figure>\n<h3>Preven\u00e7\u00e3o de Rachaduras<\/h3>\n<p>Um problema comum que surge durante os processos de dobra do alum\u00ednio \u00e9 a rachadura em chapas grandes. Isso acontece quando o material \u00e9 submetido a uma for\u00e7a de flex\u00e3o excessiva, levando \u00e0 concentra\u00e7\u00e3o de tens\u00f5es e falha. Para evitar esse problema, \u00e9 essencial preparar adequadamente o tecido, recozindo ou aquecendo-o antes de dobr\u00e1-lo. Esse processo ajuda a reduzir a dureza e aumentar a flexibilidade do material, permitindo que ele suporte a for\u00e7a de flex\u00e3o sem rachar. Tamb\u00e9m \u00e9 recomendado o uso de ferramentas adequadas, incluindo matrizes e mandris de suporte, para evitar qualquer chance de quebra.<\/p>\n<h3>Resist\u00eancia ao escoamento vs. Resist\u00eancia \u00e0 tra\u00e7\u00e3o<\/h3>\n<figure id=\"attachment_10429\" aria-describedby=\"caption-attachment-10429\" style=\"width: 440px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-10429\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-37.png\" alt=\"Tens\u00e3o - curva de deforma\u00e7\u00e3o para um material d\u00factil\" width=\"440\" height=\"286\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-37.png 440w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-37-300x195.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-37-18x12.png 18w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-37-250x163.png 250w\" sizes=\"(max-width: 440px) 100vw, 440px\"><figcaption id=\"caption-attachment-10429\" class=\"wp-caption-text\"><strong>Tens\u00e3o - curva de deforma\u00e7\u00e3o para um material d\u00factil<\/strong><\/figcaption><\/figure>\n<p>Outro fator cr\u00edtico na dobra do alum\u00ednio \u00e9 a diferen\u00e7a entre o escoamento e a resist\u00eancia \u00e0 tra\u00e7\u00e3o. A resist\u00eancia ao escoamento refere-se \u00e0 quantidade m\u00e1xima de tens\u00e3o que um material pode suportar antes de come\u00e7ar a se deformar plasticamente. Em contraste, a resist\u00eancia \u00e0 tra\u00e7\u00e3o refere-se \u00e0 press\u00e3o m\u00e1xima que um material pode suportar antes de fraturar. \u00c9 fundamental entender esses dois conceitos para otimizar o processo de dobra. Geralmente, um maior limite de elasticidade fornece um melhor resultado de dobra, permitindo que o material se deforme sem fraturar.<\/p>\n<h3>T\u00e9cnicas para obter \u00e2ngulos de dobra desejados<\/h3>\n<figure id=\"attachment_10428\" aria-describedby=\"caption-attachment-10428\" style=\"width: 534px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10428\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-36.png\" alt=\"Imagens macro de esp\u00e9cimes ap\u00f3s o teste de flex\u00e3o: a 1# ZL205A, b 2# Cf\/Al comp\u00f3sito ec 3# Cf\/Al comp\u00f3sito com defeito de superf\u00edcie\" width=\"534\" height=\"704\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-36.png 534w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-36-228x300.png 228w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-36-9x12.png 9w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-36-152x200.png 152w\" sizes=\"(max-width: 534px) 100vw, 534px\"><figcaption id=\"caption-attachment-10428\" class=\"wp-caption-text\"><strong>Imagens macro de corpos de prova ap\u00f3s o teste de flex\u00e3o: um 1# ZL205A,<\/strong><br><strong>b Comp\u00f3sito 2# Cf\/Al, ec Comp\u00f3sito 3# Cf\/Al com defeito de superf\u00edcie<\/strong><\/figcaption><\/figure>\n<p>Alcan\u00e7ar o \u00e2ngulo de dobra desejado \u00e9 uma etapa crucial na dobra de alum\u00ednio. V\u00e1rias t\u00e9cnicas podem ser usadas para conseguir isso, incluindo dobragem a ar, dobragem inferior e cunhagem. A dobragem a ar \u00e9 a t\u00e9cnica mais comum, onde o material \u00e9 deformado pela aplica\u00e7\u00e3o de for\u00e7a no topo da chapa, deixando um espa\u00e7o entre a chapa e a matriz. Em contraste, a dobra inferior envolve o uso de press\u00e3o na parte inferior da chapa, resultando em um raio de dobra mais estreito. A cunhagem \u00e9 uma t\u00e9cnica que consiste em comprimir o material em uma forma ou \u00e2ngulo espec\u00edfico usando uma matriz que corresponda exatamente \u00e0 condi\u00e7\u00e3o do material.<\/p>\n<h3>Desafios de Formabilidade de Certas Ligas de Alum\u00ednio<\/h3>\n<p>Algumas ligas de alum\u00ednio apresentam desafios na conformabilidade, especialmente aquelas com alto teor de elementos de liga espec\u00edficos, como magn\u00e9sio, cobre e l\u00edtio. Essas ligas t\u00eam flexibilidade reduzida e maior elasticidade, alcan\u00e7ando dif\u00edceis \u00e2ngulos de curvatura. Para contornar esse problema, recomenda-se o uso de ligas recozidas ou tratadas termicamente, que possuem maior flexibilidade e s\u00e3o mais adequadas para flex\u00e3o.<\/p>\n<h3>Considera\u00e7\u00f5es sobre resist\u00eancia \u00e0 corros\u00e3o<\/h3>\n<p>Outro fator a considerar na dobra de alum\u00ednio \u00e9 <a class=\"wpil_keyword_link\" href=\"https:\/\/china-maching.com\/pt\/o-guia-definitivo-para-resistencia-a-corrosao\/\" target=\"_blank\" rel=\"noopener\" title=\"resist\u00eancia \u00e0 corros\u00e3o\" data-wpil-keyword-link=\"linked\">resist\u00eancia \u00e0 corros\u00e3o<\/a>. Dependendo da aplica\u00e7\u00e3o, o material de alum\u00ednio pode ficar exposto a ambientes agressivos que podem causar corros\u00e3o. Para evitar isso, a superf\u00edcie do material deve ser adequadamente preparada, removendo contaminantes e aplicando uma camada protetora, como anodiza\u00e7\u00e3o ou pintura. Isto ajudar\u00e1 a aumentar a resist\u00eancia \u00e0 corros\u00e3o do material e prolongar a sua vida \u00fatil.<\/p>\n<h2>Escolhendo o melhor alum\u00ednio para dobrar<\/h2>\n<figure id=\"attachment_10427\" aria-describedby=\"caption-attachment-10427\" style=\"width: 781px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10427\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35.png\" alt=\"Ilustra\u00e7\u00e3o esquem\u00e1tica da configura\u00e7\u00e3o do teste de flex\u00e3o de tr\u00eas pontos (dimens\u00f5es em mm)\" width=\"781\" height=\"478\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35.png 781w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35-300x184.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35-768x470.png 768w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35-18x12.png 18w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/1-35-250x153.png 250w\" sizes=\"(max-width: 781px) 100vw, 781px\"><figcaption id=\"caption-attachment-10427\" class=\"wp-caption-text\"><strong>Ilustra\u00e7\u00e3o esquem\u00e1tica da configura\u00e7\u00e3o do teste de flex\u00e3o de tr\u00eas pontos (dimens\u00f5es em mm)<\/strong><\/figcaption><\/figure>\n<h3>Quais ligas de alum\u00ednio s\u00e3o mais adequadas para dobrar?<\/h3>\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/china-maching.com\/pt\/guia-completo-para-desenho-cad-para-maquina-cnc\/\" class=\"template-9\"><img width=\"200\" height=\"200\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/1-8.png\" class=\"alignleft wp-post-image\" alt=\"Guia abrangente para desenho CAD para m\u00e1quina CNC\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/1-8.png 512w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/1-8-300x300.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/1-8-150x150.png 150w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/1-8-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\"><div class=\"postTitle\"><span><strong>Ler mais<\/strong>Guia abrangente para desenho CAD para m\u00e1quina CNC<\/span><\/div><\/a><\/div><p>As ligas de alum\u00ednio s\u00e3o classificadas com base em sua composi\u00e7\u00e3o qu\u00edmica e propriedades mec\u00e2nicas. Algumas ligas s\u00e3o mais adequadas para flex\u00e3o do que outras devido \u00e0 sua deformabilidade sem rachaduras ou quebras. As ligas da s\u00e9rie 3xxx, como 3003 e 3105, s\u00e3o comumente usadas para aplica\u00e7\u00f5es de dobra devido \u00e0 sua excelente conformabilidade e ductilidade. Essas ligas tamb\u00e9m s\u00e3o acess\u00edveis e prontamente dispon\u00edveis, tornando-as populares entre os fabricantes industriais.<\/p>\n<h3>Qual \u00e9 a rela\u00e7\u00e3o entre a espessura do alum\u00ednio e o raio de curvatura?<\/h3>\n<p>A espessura de uma folha de alum\u00ednio \u00e9 diretamente proporcional ao raio de curvatura m\u00ednimo que pode ser alcan\u00e7ado sem causar rachaduras ou fraturas. Quanto mais espessa a chapa, maior o raio de curvatura para evitar deforma\u00e7\u00f5es. Geralmente, chapas de alum\u00ednio mais espessas requerem m\u00e1quinas de dobra maiores e mais for\u00e7a para obter a forma desejada. O raio de curvatura pode ser calculado usando f\u00f3rmulas espec\u00edficas e deve ser considerado ao selecionar a liga de alum\u00ednio apropriada para uma aplica\u00e7\u00e3o de dobra.<\/p>\n<h3>Como a capacidade de dobra da liga afeta o processo de dobra?<\/h3>\n<p>A capacidade de uma liga de alum\u00ednio ser dobrada sem rachar ou quebrar \u00e9 determinada por suas propriedades mec\u00e2nicas, como resist\u00eancia \u00e0 tra\u00e7\u00e3o e resist\u00eancia ao escoamento. Ligas com maior flexibilidade e propriedades de alongamento s\u00e3o mais adequadas para aplica\u00e7\u00f5es de dobra. A liga escolhida tamb\u00e9m deve equilibrar bem pot\u00eancia e conformabilidade para garantir durabilidade e facilidade de torneamento durante a fabrica\u00e7\u00e3o.<\/p>\n<p><strong>Recomendar Leitura:<\/strong> <a href=\"https:\/\/china-maching.com\/pt\/dobra-de-tubos\/\" target=\"_blank\">DOBRAGEM DE TUBO<\/a><\/p>\n<h3>Quais s\u00e3o as vantagens e desvantagens de usar o alum\u00ednio 3003?<\/h3>\n<p>O alum\u00ednio 3003 \u00e9 popular para aplica\u00e7\u00f5es de dobra devido \u00e0 sua excelente conformabilidade e economia. Possui alta resist\u00eancia \u00e0 corros\u00e3o e \u00e9 f\u00e1cil de soldar e usinar. No entanto, o alum\u00ednio 3003 n\u00e3o \u00e9 t\u00e3o forte quanto outras ligas, o que o torna menos adequado para aplica\u00e7\u00f5es que exigem alta resist\u00eancia. Ele tamb\u00e9m tem um ponto de fus\u00e3o mais baixo do que outras ligas, o que pode ser uma preocupa\u00e7\u00e3o em ambientes de alta temperatura.<\/p>\n<h3>Entendendo as diferen\u00e7as na dobra de alum\u00ednio e a\u00e7o<\/h3>\n<p>A dobra de alum\u00ednio e a\u00e7o requer diferentes t\u00e9cnicas e equipamentos. O a\u00e7o geralmente \u00e9 mais dif\u00edcil de tornear devido \u00e0 sua alta resist\u00eancia, o que requer mais for\u00e7a e m\u00e1quinas de dobra maiores. Por outro lado, o alum\u00ednio \u00e9 mais male\u00e1vel e pode ser torneado com menos energia e m\u00e1quinas menores. No entanto, o alum\u00ednio tem uma resist\u00eancia \u00e0 fadiga menor do que o a\u00e7o, tornando-o mais propenso a rachaduras com o tempo. Os fabricantes industriais devem considerar as diferen\u00e7as entre esses materiais ao selecionar o material mais apropriado para suas aplica\u00e7\u00f5es espec\u00edficas.<\/p>\n<p><strong>Recomendar Leitura: <a href=\"https:\/\/china-maching.com\/pt\/corte-de-folhas\/\" target=\"_blank\">Descubra o poder do corte de chapas!<\/a><br>\n<\/strong><\/p>\n<h2>perguntas frequentes<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10425\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16.png\" alt=\"perguntas frequentes\" width=\"512\" height=\"512\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16.png 512w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16-300x300.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16-150x150.png 150w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16-12x12.png 12w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/3-16-200x200.png 200w\" sizes=\"(max-width: 512px) 100vw, 512px\"><\/p>\n<h3>P: O que \u00e9 dobra de alum\u00ednio?<\/h3>\n<p>R: A dobra de alum\u00ednio refere-se ao processo de moldar folhas ou placas de alum\u00ednio, for\u00e7ando-as em \u00e2ngulos ou curvas desejadas.<\/p>\n<h3>P: Quais t\u00e9cnicas s\u00e3o usadas para dobrar alum\u00ednio?<\/h3>\n<p>R: V\u00e1rias t\u00e9cnicas podem ser usadas para dobrar alum\u00ednio, como usar um freio de dobra de metal, criar uma linha de dobra, prender o alum\u00ednio e aplicar for\u00e7a para dobrar a chapa de metal.<\/p>\n<h3>P: Quais s\u00e3o os fatores essenciais a serem considerados ao dobrar alum\u00ednio?<\/h3>\n<p>R: Ao dobrar o alum\u00ednio, \u00e9 essencial considerar o tipo de liga de alum\u00ednio que est\u00e1 sendo usada, a localiza\u00e7\u00e3o da linha de dobra, o \u00e2ngulo desejado da dobra e o rendimento e a resist\u00eancia \u00e0 tra\u00e7\u00e3o do alum\u00ednio.<\/p>\n<h3>P: Quais ligas de alum\u00ednio s\u00e3o melhores para dobrar?<\/h3>\n<p>R: Algumas ligas de alum\u00ednio s\u00e3o projetadas especificamente para dobrar e s\u00e3o conhecidas por terem boa formabilidade. Ligas como o alum\u00ednio 3003 s\u00e3o comumente usadas para aplica\u00e7\u00f5es de torneamento.<\/p>\n<h3>P: O alum\u00ednio pode ser dobrado sem rachar?<\/h3>\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/china-maching.com\/pt\/fillet-radii-tudo-que-voce-precisa-saber\/\" class=\"template-9\"><img width=\"200\" height=\"200\" src=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/2-7.png\" class=\"alignleft wp-post-image\" alt=\"Raios de filete: tudo o que voc\u00ea precisa saber\" srcset=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/2-7.png 512w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/2-7-300x300.png 300w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/2-7-150x150.png 150w, https:\/\/china-maching.com\/wp-content\/uploads\/2023\/05\/2-7-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\"><div class=\"postTitle\"><span><strong>Ler mais<\/strong>Raios de filete: tudo o que voc\u00ea precisa saber<\/span><\/div><\/a><\/div><p>R: O alum\u00ednio pode ser dobrado sem rachaduras se forem usadas as t\u00e9cnicas corretas e as ferramentas adequadas. \u00c9 essencial escolher a liga adequada para dobrar e garantir que o processo de dobra seja feito com cuidado.<\/p>\n<h3>P: Qu\u00e3o dif\u00edcil \u00e9 formar alum\u00ednio?<\/h3>\n<p>R: A dificuldade de moldar o alum\u00ednio depende de v\u00e1rios fatores, incluindo a liga espec\u00edfica que est\u00e1 sendo usada, a espessura da folha ou chapa de alum\u00ednio e o formato ou \u00e2ngulo desejado. Algumas ligas de alum\u00ednio podem ser formadas mais facilmente do que outras.<\/p>\n<h3>P: Existe uma t\u00e9cnica de dobra espec\u00edfica para dobrar grandes pe\u00e7as de alum\u00ednio?<\/h3>\n<p>R: Ao dobrar pe\u00e7as grandes de alum\u00ednio, geralmente \u00e9 necess\u00e1rio um freio de dobra de metal ou outro equipamento especializado para obter dobras precisas e precisas.<\/p>\n<h3>P: Como posso determinar a linha de dobra para dobra de alum\u00ednio?<\/h3>\n<p>R: A linha de dobra para dobra de alum\u00ednio pode ser determinada usando uma ferramenta de localiza\u00e7\u00e3o de \u00e2ngulo ou marcando um local espec\u00edfico onde a dobra deve ocorrer na folha de metal.<\/p>\n<h3>P: Como devo prender o alum\u00ednio para dobrar?<\/h3>\n<p>R: Na fixa\u00e7\u00e3o do alum\u00ednio para dobra, \u00e9 imprescind\u00edvel o uso de um grampo adequado \u00e0 espessura e tamanho da chapa de alum\u00ednio. A bra\u00e7adeira deve ser posicionada na linha de dobra desejada, garantindo que o alum\u00ednio seja segurado com seguran\u00e7a durante a dobra.<\/p>\n<h3>P: Posso usar alum\u00ednio para um reparo de bricolage?<\/h3>\n<p>R: O alum\u00ednio pode ser adequado para reparos de bricolage em alguns casos. Se voc\u00ea precisa dobrar ou moldar alum\u00ednio para um reparo de bricolage, \u00e9 importante escolher a liga adequada para dobrar e seguir as t\u00e9cnicas adequadas para evitar rachaduras ou danos ao metal.<\/p>","protected":false},"excerpt":{"rendered":"<p>How to Bend Aluminum Bending aluminum is deforming the metal to form a curve or angle. It is an essential technique in various industries, including construction, automotive, and aerospace. Aluminum&rsquo;s lightweight, durable, and corrosion-resistant properties make it a popular choice for many applications. However, bending aluminum requires knowledge and skills to ensure successful results. What [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cnc-machining-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aluminum Bending: Techniques and Tips - ETCN<\/title>\n<meta name=\"description\" content=\"ETCN about: Uncover the historical context and modern practices of Aluminum Bending. Harness our comprehensive guide for precision bending. Explore today!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/china-maching.com\/pt\/tecnicas-e-pontas-de-dobra-de-aluminio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Bending: Techniques and Tips\" \/>\n<meta property=\"og:description\" content=\"ETCN about: Uncover the historical context and modern practices of Aluminum Bending. Harness our comprehensive guide for precision bending. Explore today!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/china-maching.com\/pt\/tecnicas-e-pontas-de-dobra-de-aluminio\/\" \/>\n<meta property=\"og:site_name\" content=\"ETCN\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T06:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-29T01:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jasonxue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jasonxue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/\"},\"author\":{\"name\":\"Jasonxue\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/#\\\/schema\\\/person\\\/d59d3ec84c559ab5c3ae27cb3f15e746\"},\"headline\":\"Aluminum Bending: Techniques and Tips\",\"datePublished\":\"2023-08-18T06:14:09+00:00\",\"dateModified\":\"2023-08-29T01:57:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/\"},\"wordCount\":1876,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-24.png\",\"articleSection\":[\"CNC Machining Blog\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/\",\"url\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/\",\"name\":\"Aluminum Bending: Techniques and Tips - ETCN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-24.png\",\"datePublished\":\"2023-08-18T06:14:09+00:00\",\"dateModified\":\"2023-08-29T01:57:50+00:00\",\"description\":\"ETCN about: Uncover the historical context and modern practices of Aluminum Bending. Harness our comprehensive guide for precision bending. Explore today!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#primaryimage\",\"url\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-24.png\",\"contentUrl\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-24.png\",\"width\":512,\"height\":512,\"caption\":\"Aluminum Bending: Techniques and Tips\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/aluminum-bending-techniques-and-tips\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/china-maching.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aluminum Bending: Techniques and Tips\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/#website\",\"url\":\"https:\\\/\\\/china-maching.com\\\/\",\"name\":\"ETCN\",\"description\":\"China&#039;s top CNC Machining Services Supplier\",\"publisher\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/china-maching.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/#organization\",\"name\":\"ETCN\",\"url\":\"https:\\\/\\\/china-maching.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-ETCN.png\",\"contentUrl\":\"https:\\\/\\\/china-maching.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-ETCN.png\",\"width\":511,\"height\":171,\"caption\":\"ETCN\"},\"image\":{\"@id\":\"https:\\\/\\\/china-maching.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/china-maching.com\\\/#\\\/schema\\\/person\\\/d59d3ec84c559ab5c3ae27cb3f15e746\",\"name\":\"Jasonxue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"caption\":\"Jasonxue\"},\"sameAs\":[\"https:\\\/\\\/china-maching.com\"],\"url\":\"https:\\\/\\\/china-maching.com\\\/pt\\\/author\\\/jasonxue\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dobragem de Alum\u00ednio: T\u00e9cnicas e Dicas - ETCN","description":"ETCN sobre: Descubra o contexto hist\u00f3rico e as pr\u00e1ticas modernas de dobra de alum\u00ednio. Aproveite nosso guia abrangente para dobra de precis\u00e3o. Explore hoje!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/china-maching.com\/pt\/tecnicas-e-pontas-de-dobra-de-aluminio\/","og_locale":"pt_PT","og_type":"article","og_title":"Aluminum Bending: Techniques and Tips","og_description":"ETCN about: Uncover the historical context and modern practices of Aluminum Bending. Harness our comprehensive guide for precision bending. Explore today!","og_url":"https:\/\/china-maching.com\/pt\/tecnicas-e-pontas-de-dobra-de-aluminio\/","og_site_name":"ETCN","article_published_time":"2023-08-18T06:14:09+00:00","article_modified_time":"2023-08-29T01:57:50+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png","type":"image\/png"}],"author":"Jasonxue","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jasonxue","Tempo estimado de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#article","isPartOf":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/"},"author":{"name":"Jasonxue","@id":"https:\/\/china-maching.com\/#\/schema\/person\/d59d3ec84c559ab5c3ae27cb3f15e746"},"headline":"Aluminum Bending: Techniques and Tips","datePublished":"2023-08-18T06:14:09+00:00","dateModified":"2023-08-29T01:57:50+00:00","mainEntityOfPage":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/"},"wordCount":1876,"commentCount":0,"publisher":{"@id":"https:\/\/china-maching.com\/#organization"},"image":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#primaryimage"},"thumbnailUrl":"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png","articleSection":["CNC Machining Blog"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/","url":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/","name":"Dobragem de Alum\u00ednio: T\u00e9cnicas e Dicas - ETCN","isPartOf":{"@id":"https:\/\/china-maching.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#primaryimage"},"image":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#primaryimage"},"thumbnailUrl":"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png","datePublished":"2023-08-18T06:14:09+00:00","dateModified":"2023-08-29T01:57:50+00:00","description":"ETCN sobre: Descubra o contexto hist\u00f3rico e as pr\u00e1ticas modernas de dobra de alum\u00ednio. Aproveite nosso guia abrangente para dobra de precis\u00e3o. Explore hoje!","breadcrumb":{"@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#primaryimage","url":"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png","contentUrl":"https:\/\/china-maching.com\/wp-content\/uploads\/2023\/08\/2-24.png","width":512,"height":512,"caption":"Aluminum Bending: Techniques and Tips"},{"@type":"BreadcrumbList","@id":"https:\/\/china-maching.com\/aluminum-bending-techniques-and-tips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/china-maching.com\/"},{"@type":"ListItem","position":2,"name":"Aluminum Bending: Techniques and Tips"}]},{"@type":"WebSite","@id":"https:\/\/china-maching.com\/#website","url":"https:\/\/china-maching.com\/","name":"ETCN","description":"China &amp; #039;s principal fornecedor de servi\u00e7os de usinagem CNC","publisher":{"@id":"https:\/\/china-maching.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/china-maching.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/china-maching.com\/#organization","name":"ETCN","url":"https:\/\/china-maching.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/china-maching.com\/#\/schema\/logo\/image\/","url":"https:\/\/china-maching.com\/wp-content\/uploads\/2024\/02\/cropped-ETCN.png","contentUrl":"https:\/\/china-maching.com\/wp-content\/uploads\/2024\/02\/cropped-ETCN.png","width":511,"height":171,"caption":"ETCN"},"image":{"@id":"https:\/\/china-maching.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/china-maching.com\/#\/schema\/person\/d59d3ec84c559ab5c3ae27cb3f15e746","name":"Jasonxue","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","caption":"Jasonxue"},"sameAs":["https:\/\/china-maching.com"],"url":"https:\/\/china-maching.com\/pt\/author\/jasonxue\/"}]}},"_links":{"self":[{"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/posts\/10421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/comments?post=10421"}],"version-history":[{"count":2,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/posts\/10421\/revisions"}],"predecessor-version":[{"id":10819,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/posts\/10421\/revisions\/10819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/media\/10424"}],"wp:attachment":[{"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/media?parent=10421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/categories?post=10421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/china-maching.com\/pt\/wp-json\/wp\/v2\/tags?post=10421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}